{"id":891,"date":"2024-02-01T08:30:00","date_gmt":"2024-02-01T07:30:00","guid":{"rendered":"https:\/\/www.lepointdepolgara.fr\/?p=891"},"modified":"2024-01-28T16:44:46","modified_gmt":"2024-01-28T15:44:46","slug":"interview-melville-tilh-plunvenn","status":"publish","type":"post","link":"https:\/\/www.lepointdepolgara.fr\/index.php\/2024\/02\/01\/interview-melville-tilh-plunvenn\/","title":{"rendered":"Interview &#8211; Melville Tilh-Plunvenn"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Melville revient sur sa d\u00e9couverte du jeu de r\u00f4le ado avec Donjons et dragons, puis ses d\u00e9couvertes et les jeux qui l&rsquo;ont incit\u00e9e \u00e0 explorer une autre forme de narration, et notamment <em>Wushu <\/em>de <strong>Simon Wahsbourne<\/strong> ou encore <strong>R\u00eave de dragon<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Suite \u00e0 l&rsquo;\u00e9volution amen\u00e9e fin des ann\u00e9es 2000 avec le syst\u00e8me <em>Powered By The Apocalypse<\/em> (PBTA), elle s&rsquo;int\u00e9resse \u00e0 des syst\u00e8mes de jeu plus radicaux dans la lign\u00e9e des cr\u00e9ations de <strong>Avery Alder<\/strong>, avec notamment <em>Monsterhearts<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parmi ses cr\u00e9ations, certaines reprenant le syst\u00e8me <em>Belonging Outside Belonging<\/em> (BOB) sans meneuse et sans d\u00e9,  <strong>Melville <\/strong>propose notamment :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La t\u00e9tralogie <em>Les Couleurs de l&rsquo;amiti\u00e9<\/em> compos\u00e9e de <em>Trois Jours de soleil<\/em>, <em>Quelque part sur la route<\/em>, <em>Se souvenir de Novembre <\/em>et <em>Les Bourgeons<\/em>, qui explore les relations amicales entre les personnages des joueuses \u00e0 des moments cruciaux de leur existence. Les quatre sc\u00e9narios sont disponibles sous format pdf <a href=\"https:\/\/itch.io\/c\/1351145\/colours-of-friendship-des-couleurs-de-lamiti\" data-type=\"link\" data-id=\"https:\/\/itch.io\/c\/1351145\/colours-of-friendship-des-couleurs-de-lamiti\">ici<\/a>.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"627\" height=\"743\" src=\"https:\/\/www.lepointdepolgara.fr\/wp-content\/uploads\/2024\/01\/Capture-decran-2024-01-26-164553.png\" alt=\"\" class=\"wp-image-895\" style=\"width:276px;height:auto\" srcset=\"https:\/\/www.lepointdepolgara.fr\/wp-content\/uploads\/2024\/01\/Capture-decran-2024-01-26-164553.png 627w, https:\/\/www.lepointdepolgara.fr\/wp-content\/uploads\/2024\/01\/Capture-decran-2024-01-26-164553-253x300.png 253w\" sizes=\"auto, (max-width: 627px) 100vw, 627px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>Bois dormant<\/em>, illustr\u00e9 par <strong>Je suis une l\u00e9gume <\/strong>et \u00e9dit\u00e9 par <strong><a href=\"https:\/\/www.dystopia.fr\/a\/melville\/bois-dormant\" data-type=\"link\" data-id=\"https:\/\/www.dystopia.fr\/a\/melville\/bois-dormant\">Dystopia<\/a><\/strong>, qui plonge les joueuses dans une cit\u00e9 dont une partie de la population est endormie et dont elles doivent prendre soin.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"372\" height=\"372\" src=\"https:\/\/www.lepointdepolgara.fr\/wp-content\/uploads\/2024\/01\/bois-dormant.jpg\" alt=\"\" class=\"wp-image-896\" style=\"width:360px;height:auto\" srcset=\"https:\/\/www.lepointdepolgara.fr\/wp-content\/uploads\/2024\/01\/bois-dormant.jpg 372w, https:\/\/www.lepointdepolgara.fr\/wp-content\/uploads\/2024\/01\/bois-dormant-300x300.jpg 300w, https:\/\/www.lepointdepolgara.fr\/wp-content\/uploads\/2024\/01\/bois-dormant-150x150.jpg 150w\" sizes=\"auto, (max-width: 372px) 100vw, 372px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>L&rsquo;Insurrection<\/em>, illustr\u00e9 par <strong>Willy Cabourdin<\/strong> et \u00e9dit\u00e9 par <a href=\"https:\/\/electric-goat.net\/insurrection\" data-type=\"link\" data-id=\"https:\/\/electric-goat.net\/insurrection\"><strong>Electric Goat<\/strong><\/a>, un jeu pour parle de la grande politique, de la r\u00e9volution et de l&rsquo;opposition des diff\u00e9rentes forces en pr\u00e9sence.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"665\" height=\"1024\" src=\"https:\/\/www.lepointdepolgara.fr\/wp-content\/uploads\/2023\/12\/FrFmuBnXwAAVZDT-768x1183-1-665x1024.jpg\" alt=\"\" class=\"wp-image-755\" style=\"width:268px;height:auto\" srcset=\"https:\/\/www.lepointdepolgara.fr\/wp-content\/uploads\/2023\/12\/FrFmuBnXwAAVZDT-768x1183-1-665x1024.jpg 665w, https:\/\/www.lepointdepolgara.fr\/wp-content\/uploads\/2023\/12\/FrFmuBnXwAAVZDT-768x1183-1-195x300.jpg 195w, https:\/\/www.lepointdepolgara.fr\/wp-content\/uploads\/2023\/12\/FrFmuBnXwAAVZDT-768x1183-1.jpg 768w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Melville <\/strong>\u00e9voque \u00e9galement les diff\u00e9rentes fa\u00e7ons de raconter une histoire commune que proposent le jeu de r\u00f4le, ainsi que les diff\u00e9rences entre les jeux men\u00e9s par l&rsquo;intrigue (<em>Plot driven<\/em>) et ceux men\u00e9s par les personnages (<em>Character driven<\/em>). Elle explique aussi rapidement les jeux dits <em>Firebrands<\/em>, tirant leur syst\u00e8me du jeu de r\u00f4le \u00e9ponyme cr\u00e9\u00e9 par <strong>Vincent D. Baker<\/strong>, t\u00e9l\u00e9chargeable <a href=\"https:\/\/www.firebrands.fr\/\" data-type=\"link\" data-id=\"https:\/\/www.firebrands.fr\/\">ici<\/a>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfin, <strong>Melville <\/strong>parle de jeux \u00e0 la fronti\u00e8re entre jeu de r\u00f4le et jeux de soci\u00e9t\u00e9 (<em>Pour la reine<\/em>, <em>Alice is missing<\/em>) et de jeux de soci\u00e9t\u00e9 tout court (<em>Unlock!<\/em>, <em>The Crew<\/em>).<\/p>\n\n<iframe name=\"Ausha Podcast Player\" frameborder=\"0\" loading=\"lazy\" id=\"ausha-3XU0\" height=\"220\" style=\"border: none; width:100%; height:220px\" src=\"https:\/\/player.ausha.co\/?showId=2PN36tY9RQZr&#038;color=%2372238e&#038;podcastId=XZXqDcpp0J4k&#038;v=3&#038;playerId=ausha-3XU0\"><\/iframe><script src=\"https:\/\/player.ausha.co\/ausha-player.js\"><\/script>","protected":false},"excerpt":{"rendered":"<p>Une interview de Melville Tilh-Plunvenn, autrice de jeux de r\u00f4le.<\/p>\n","protected":false},"author":2,"featured_media":901,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[168,63],"tags":[252,338,339,343,341,340,344,337,262,261,335,336,334,342],"class_list":["post-891","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interview","category-podcast","tag-belonging-outside-belonging","tag-bois-dormant","tag-dystopia","tag-electric-goat","tag-firebrands","tag-je-suis-une-legume","tag-la-fille-da-cote","tag-les-bourgeons","tag-les-couleurs-de-lamitie","tag-melville-tilh-plunvenn","tag-quelque-part-sur-la-route","tag-se-souvenir-de-novembre","tag-trois-jours-de-soleil","tag-willy-cabourdin"],"_links":{"self":[{"href":"https:\/\/www.lepointdepolgara.fr\/index.php\/wp-json\/wp\/v2\/posts\/891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lepointdepolgara.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lepointdepolgara.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lepointdepolgara.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lepointdepolgara.fr\/index.php\/wp-json\/wp\/v2\/comments?post=891"}],"version-history":[{"count":8,"href":"https:\/\/www.lepointdepolgara.fr\/index.php\/wp-json\/wp\/v2\/posts\/891\/revisions"}],"predecessor-version":[{"id":902,"href":"https:\/\/www.lepointdepolgara.fr\/index.php\/wp-json\/wp\/v2\/posts\/891\/revisions\/902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lepointdepolgara.fr\/index.php\/wp-json\/wp\/v2\/media\/901"}],"wp:attachment":[{"href":"https:\/\/www.lepointdepolgara.fr\/index.php\/wp-json\/wp\/v2\/media?parent=891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lepointdepolgara.fr\/index.php\/wp-json\/wp\/v2\/categories?post=891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lepointdepolgara.fr\/index.php\/wp-json\/wp\/v2\/tags?post=891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}